{"id":107,"count":8,"description":"","link":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/","name":"Pizza","slug":"pizza-es","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Mess Dondurulmu\u015f Pizza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/\",\"url\":\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/\",\"name\":\"Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza\",\"isPartOf\":{\"@id\":\"https:\/\/messgida.com.tr\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\/\/messgida.com.tr\/es\/pagina-de-inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pizza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/messgida.com.tr\/es\/#website\",\"url\":\"https:\/\/messgida.com.tr\/es\/\",\"name\":\"Mess Dondurulmu\u015f Pizza\",\"description\":\"Tazeli\u011fin \u0130zinde Dondurulmu\u015f Lezzetler\",\"publisher\":{\"@id\":\"https:\/\/messgida.com.tr\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/messgida.com.tr\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/messgida.com.tr\/es\/#organization\",\"name\":\"Mess Dondurulmu\u015f Pizza\",\"url\":\"https:\/\/messgida.com.tr\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/messgida.com.tr\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/messgida.com.tr\/wp-content\/uploads\/2023\/02\/messgida-logo-dark.svg\",\"contentUrl\":\"https:\/\/messgida.com.tr\/wp-content\/uploads\/2023\/02\/messgida-logo-dark.svg\",\"width\":250,\"height\":46.07,\"caption\":\"Mess Dondurulmu\u015f Pizza\"},\"image\":{\"@id\":\"https:\/\/messgida.com.tr\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/messgida\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/","og_locale":"es_ES","og_type":"article","og_title":"Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza","og_url":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/","og_site_name":"Mess Dondurulmu\u015f Pizza","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/","url":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/","name":"Pizza ar\u015fivleri - Mess Dondurulmu\u015f Pizza","isPartOf":{"@id":"https:\/\/messgida.com.tr\/es\/#website"},"breadcrumb":{"@id":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/messgida.com.tr\/es\/urun-kategori\/pizza-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/messgida.com.tr\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Pizza"}]},{"@type":"WebSite","@id":"https:\/\/messgida.com.tr\/es\/#website","url":"https:\/\/messgida.com.tr\/es\/","name":"Mess Dondurulmu\u015f Pizza","description":"Tazeli\u011fin \u0130zinde Dondurulmu\u015f Lezzetler","publisher":{"@id":"https:\/\/messgida.com.tr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/messgida.com.tr\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/messgida.com.tr\/es\/#organization","name":"Mess Dondurulmu\u015f Pizza","url":"https:\/\/messgida.com.tr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/messgida.com.tr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/messgida.com.tr\/wp-content\/uploads\/2023\/02\/messgida-logo-dark.svg","contentUrl":"https:\/\/messgida.com.tr\/wp-content\/uploads\/2023\/02\/messgida-logo-dark.svg","width":250,"height":46.07,"caption":"Mess Dondurulmu\u015f Pizza"},"image":{"@id":"https:\/\/messgida.com.tr\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/messgida"]}]}},"_links":{"self":[{"href":"https:\/\/messgida.com.tr\/es\/wp-json\/wp\/v2\/product_cat\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/messgida.com.tr\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/messgida.com.tr\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/messgida.com.tr\/es\/wp-json\/wp\/v2\/product?product_cat=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}